{"id":110918,"date":"2023-12-15T14:30:38","date_gmt":"2023-12-15T17:30:38","guid":{"rendered":"https:\/\/aliensdesign.com.br\/?p=110918"},"modified":"2024-04-18T14:24:33","modified_gmt":"2024-04-18T17:24:33","slug":"tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico","status":"publish","type":"post","link":"https:\/\/aliensdesign.com.br\/en\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/","title":{"rendered":"Tipografia: como escolher a fonte para o seu projeto"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-dark\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode_text_column\" ><p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa pode ser crucial para o sucesso visual do seu projeto. Se voc\u00ea est\u00e1 se perguntando por onde come\u00e7ar ao escolher a tipografia adequada, este guia pr\u00e1tico \u00e9 para voc\u00ea.<\/span><\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">A tipografia, conhecido popularmente como \u2018fonte\u2019, afeta n\u00e3o somente a est\u00e9tica como tamb\u00e9m perpassa por acessibilidade, estudos de UI e UX, e entre outros fatores no desenvolvimento de um material. Assim, separamos 7 dicas para voc\u00ea escolher corretamente qual tipografia usar e n\u00e3o errar no seu projeto.<\/span><\/p>\n<h2>O que \u00e9 tipografia?<\/h2>\n<p><span style=\"font-weight: 400;\">Segundo o\u00a0 <\/span><a href=\"https:\/\/languages.oup.com\/\"><span style=\"font-weight: 400;\">Oxford Languages<\/span><\/a><span style=\"font-weight: 400;\">, a tipografia \u00e9 \u201cconjunto de procedimentos art\u00edsticos e t\u00e9cnicos que abrangem as diversas etapas da produ\u00e7\u00e3o gr\u00e1fica (desde a cria\u00e7\u00e3o dos caracteres at\u00e9 a impress\u00e3o e acabamento), esp. no sistema de impress\u00e3o direta com o uso de matriz em relevo; imprensa&#8221;. <\/span>Em outras palavras, <strong>a tipografia \u00e9 a forma ou apar\u00eancia do texto<\/strong>, representada pelo design e estilo das letras.<\/p>\n<p><span style=\"font-weight: 400;\">Dessa forma, ao pensarmos na tipografia como a forma das letras, \u00e9 poss\u00edvel separ\u00e1-la em 2 tipos:<\/span><\/p>\n<ul>\n<li aria-level=\"1\"><b>Fontes Serif:<\/b><span style=\"font-weight: 400;\"> s\u00e3o fontes que possuem tra\u00e7os (serifas) em suas arestas. Assim, remete a um texto mais tradicional.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_110919\" aria-describedby=\"caption-attachment-110919\" style=\"width: 840px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-110919 size-large\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-1024x574.png\" alt=\"Tipografia\" width=\"840\" height=\"471\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-1024x574.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-300x168.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-768x431.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-1536x862.png 1536w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-2048x1149.png 2048w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-18x10.png 18w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif-350x196.png 350w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/serif.png 3826w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><figcaption id=\"caption-attachment-110919\" class=\"wp-caption-text\">(Reprodu\u00e7\u00e3o: <a href=\"https:\/\/edu.gcfglobal.org\/pt\/conceitos-basicos-de-design-grafico\/o-que-e-tipografia-e-como-escolher-um-tipo-de-letra\/1\/\">GCF Global<\/a>)<\/figcaption><\/figure>\n<ul>\n<li aria-level=\"1\"><b>Fontes Sans Serif:<\/b><span style=\"font-weight: 400;\"> referenciando um texto mais direto, moderno e de f\u00e1cil escalabilidade, s\u00e3o fontes sem arestas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Veja a seguir alguns exemplos de materiais gr\u00e1ficos que utilizam fontes com e sem serifas:<\/span><\/p>\n<figure id=\"attachment_110920\" aria-describedby=\"caption-attachment-110920\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG.png\"><img decoding=\"async\" class=\"wp-image-110920 size-full\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG.png\" alt=\"Tipografia\" width=\"1200\" height=\"600\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG.png 1200w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG-300x150.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG-1024x512.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG-768x384.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG-18x9.png 18w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/ALIENS_dezembro_BLOG-350x175.png 350w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-110920\" class=\"wp-caption-text\">(Reprodu\u00e7\u00e3o: Aliens Design)<\/figcaption><\/figure>\n<h2>Como escolher a tipografia?<\/h2>\n<p><span style=\"font-weight: 400;\">Agora com a ideia do seu projeto em mente, \u00e9 necess\u00e1rio seguir algumas etapas para n\u00e3o errar a escolha da fonte e transmitir a mensagem certa.<\/span><\/p>\n<h3>#1 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Conhe\u00e7a o seu p\u00fablico-alvo<\/h3>\n<p>A tipografia deve comunicar de maneira eficaz com a audi\u00eancia-alvo; assim, refletindo a personalidade da marca e facilitando a leitura para o grupo demogr\u00e1fico espec\u00edfico.<\/p>\n<h3>#2 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Defina a personalidade da sua marca<\/h3>\n<p>Cada fonte tem sua pr\u00f3pria personalidade. Serifas tradicionais podem transmitir uma sensa\u00e7\u00e3o de formalidade; no entanto, fontes sem serifa s\u00e3o geralmente mais modernas e limpas. Escolha uma tipografia que esteja alinhada com a identidade visual da sua marca, transmitindo a mensagem certa.<\/p>\n<h3>#3 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Considere a legibilidade<\/h3>\n<p>N\u00e3o importa qu\u00e3o elegante uma fonte possa parecer; se n\u00e3o for leg\u00edvel, n\u00e3o cumprir\u00e1 seu prop\u00f3sito. Considere fatores como tamanho, espa\u00e7amento entre as letras e o contraste em rela\u00e7\u00e3o ao fundo. Al\u00e9m disso, a clareza \u00e9 fundamental para garantir que sua mensagem seja compreendida sem esfor\u00e7o.<\/p>\n<h3>#4 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Variedade adequada<\/h3>\n<p>Ao criar um design, considere a combina\u00e7\u00e3o de fontes para adicionar variedade. Ademais, escolha uma fonte principal para t\u00edtulos e uma secund\u00e1ria para o corpo do texto, garantindo que elas se complementem harmoniosamente.<\/p>\n<h3>#5 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Entenda a plataforma<\/h3>\n<p>A tipografia pode se comportar de maneira diferente em v\u00e1rios meios, como impress\u00e3o e digital. Portanto, certifique-se de testar como suas escolhas tipogr\u00e1ficas aparecem em diferentes plataformas. Isso garantir\u00e1 consist\u00eancia e efic\u00e1cia em todos os formatos.<\/p>\n<h3>#6 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Mantenha o minimalismo<\/h3>\n<p>Em alguns casos, menos \u00e9 mais. Optar por uma abordagem minimalista na escolha da tipografia pode resultar em designs mais elegantes e sofisticados. Desse modo, evite o excesso de estilos diferentes para n\u00e3o sobrecarregar visualmente o seu projeto.<\/p>\n<h3>#7 <span class=\"notion-enable-hover\" data-token-index=\"1\">\u2013 <\/span><!-- notionvc: a962e428-4064-4ab0-ae7f-5d928f66f6b1 -->Testes e ajustes<\/h3>\n<p>Antes de finalizar o design, fa\u00e7a testes com diferentes op\u00e7\u00f5es de fontes. Al\u00e9m disso, pe\u00e7a feedback de colegas ou amigos para garantir que a tipografia escolhida atenda \u00e0s expectativas e transmita a mensagem desejada.<\/p>\n<figure id=\"attachment_111123\" aria-describedby=\"caption-attachment-111123\" style=\"width: 794px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-111123\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/13429935_5258218.png\" alt=\"Tipografia\" width=\"794\" height=\"559\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/13429935_5258218.png 794w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/13429935_5258218-300x211.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/13429935_5258218-768x541.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/13429935_5258218-18x12.png 18w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/13429935_5258218-350x246.png 350w\" sizes=\"(max-width: 794px) 100vw, 794px\" \/><figcaption id=\"caption-attachment-111123\" class=\"wp-caption-text\">(Reprodu\u00e7\u00e3o: Freepik)<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Logo, fica evidente que a tipografia transcende seu papel meramente decorativo ou funcional, tornando-se uma ferramenta verdadeiramente poderosa na comunica\u00e7\u00e3o visual. <\/span><a href=\"https:\/\/aliensdesign.com.br\/en\/contato\/\"><span style=\"font-weight: 400;\">Entre em contato<\/span><\/a><span style=\"font-weight: 400;\"> com a nossa equipe agora e garanta o sucesso da sua marca.<\/span><\/p>\n<\/div><div class=\"author-profile el-author-profile author-profile-box-left\" ><div class=\"author-profile-content\"><h6 class=\"h6\"><a href=\"https:\/\/aliensdesign.com.br\/en\/author\/admin\/\"  title=\"Aliens Design post page\" target=\"_self\"><span>Aliens Design<\/span><\/a><\/h6><div class=\"contact-methods contact-methods-userid-1\">\n\t\t\t\t<ul>\n\t\t\t\t\t<li class=\"contact-method-facebook\"><a role=\"button\" href=\"https:\/\/www.facebook.com\/AliensDesign\/\" target=\"_blank\"><i class=\"fa fa-facebook\"><\/i><\/a><\/li><li class=\"contact-method-instagram\"><a role=\"button\" href=\"https:\/\/www.instagram.com\/aliensdesign\/\" target=\"_blank\"><i class=\"fa fa-instagram\"><\/i><\/a><\/li><li class=\"contact-method-linkedin\"><a role=\"button\" href=\"https:\/\/www.linkedin.com\/company\/aliens-design\/\" target=\"_blank\"><i class=\"fa fa-linkedin\"><\/i><\/a><\/li><li class=\"contact-method-link\"><a href=\"https:\/\/aliensdesign.com.br\/en\/\" target=\"_blank\"><i class=\"fa fa-link\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-xsdn-bg border-color-777586-color row-container boomapps_vcrow\" style=\"border-style: solid;\" id=\"row-unique-1\"><div class=\"row triple-top-padding triple-bottom-padding single-h-padding limit-width row-parent\" style=\"max-width:804px; margin-left:auto; margin-right:auto;\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_center column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-spec style-light animate_when_almost_visible bottom-t-top\"  data-delay=\"200\"><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_row row-internal row-container boomapps_vcrow\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_center column_child col-lg-12 boomapps_vccolumn half-internal-gutter\"><div class=\"uncol style-spec style-light\" ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" style=\" max-width:600px;\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><p class=\"font-850707 h4 fontheight-357766 font-weight-400 text-color-wvjs-color\" ><span>Want to start a project? Create or review your own brand? We work with creative and smart solutions to improve your communication!<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row row-internal row-container boomapps_vcrow\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_center column_child col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-spec style-light font-134980\" ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" style=\" max-width:804px;\" >\n\t<div class=\"wpb_raw_code wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div role=\"main\" id=\"form-leads-site-7e6d577e7bd66255a893\"><\/div>\n<script type=\"text\/javascript\" src=\"https:\/\/d335luupugsy2.cloudfront.net\/js\/rdstation-forms\/stable\/rdstation-forms.min.js\"><\/script>\n<script type=\"text\/javascript\"> new RDStationForms('form-leads-site-7e6d577e7bd66255a893', 'UA-159446367-3').createForm();<\/script>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa pode ser crucial para o sucesso visual do seu projeto. Se voc\u00ea est\u00e1 se perguntando por onde come\u00e7ar ao escolher a tipografia adequada, este guia pr\u00e1tico \u00e9 para voc\u00ea.<\/p>","protected":false},"author":1,"featured_media":110922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,86,176],"tags":[],"class_list":["post-110918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","category-design","category-arts"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tipografia: como escolher a fonte para o seu projeto<\/title>\n<meta name=\"description\" content=\"Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa \u00e9 crucial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aliensdesign.com.br\/en\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipografia: como escolher a fonte para o seu projeto\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa \u00e9 crucial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aliensdesign.com.br\/en\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliens Design\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/AliensDesign\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-15T17:30:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T17:24:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Aliens Design\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aliens Design\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/\"},\"author\":{\"name\":\"Aliens Design\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#\\\/schema\\\/person\\\/a7f1f390dd8f2e971941a7e1835bfbdd\"},\"headline\":\"Tipografia: como escolher a fonte para o seu projeto\",\"datePublished\":\"2023-12-15T17:30:38+00:00\",\"dateModified\":\"2024-04-18T17:24:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/\"},\"wordCount\":1000,\"image\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png\",\"articleSection\":[\"Dicas\",\"Design\",\"Arts\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/\",\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/\",\"name\":\"Tipografia: como escolher a fonte para o seu projeto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png\",\"datePublished\":\"2023-12-15T17:30:38+00:00\",\"dateModified\":\"2024-04-18T17:24:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#\\\/schema\\\/person\\\/a7f1f390dd8f2e971941a7e1835bfbdd\"},\"description\":\"Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa \u00e9 crucial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png\",\"contentUrl\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png\",\"width\":6720,\"height\":4480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/2023\\\/12\\\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/aliensdesign.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipografia: como escolher a fonte para o seu projeto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#website\",\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/\",\"name\":\"Aliens Design\",\"description\":\"Ag\u00eancia de Design em Curitiba!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aliensdesign.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#\\\/schema\\\/person\\\/a7f1f390dd8f2e971941a7e1835bfbdd\",\"name\":\"Aliens Design\",\"sameAs\":[\"https:\\\/\\\/aliensdesign.com.br\",\"https:\\\/\\\/www.facebook.com\\\/AliensDesign\\\/\",\"https:\\\/\\\/www.instagram.com\\\/aliensdesign\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aliens-design\\\/\"],\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipografia: como escolher a fonte para o seu projeto","description":"Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa \u00e9 crucial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aliensdesign.com.br\/en\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/","og_locale":"en_US","og_type":"article","og_title":"Tipografia: como escolher a fonte para o seu projeto","og_description":"Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa \u00e9 crucial.","og_url":"https:\/\/aliensdesign.com.br\/en\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/","og_site_name":"Aliens Design","article_author":"https:\/\/www.facebook.com\/AliensDesign\/","article_published_time":"2023-12-15T17:30:38+00:00","article_modified_time":"2024-04-18T17:24:33+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao-1024x683.png","type":"image\/png"}],"author":"Aliens Design","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aliens Design","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#article","isPartOf":{"@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/"},"author":{"name":"Aliens Design","@id":"https:\/\/aliensdesign.com.br\/#\/schema\/person\/a7f1f390dd8f2e971941a7e1835bfbdd"},"headline":"Tipografia: como escolher a fonte para o seu projeto","datePublished":"2023-12-15T17:30:38+00:00","dateModified":"2024-04-18T17:24:33+00:00","mainEntityOfPage":{"@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/"},"wordCount":1000,"image":{"@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#primaryimage"},"thumbnailUrl":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png","articleSection":["Dicas","Design","Arts"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/","url":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/","name":"Tipografia: como escolher a fonte para o seu projeto","isPartOf":{"@id":"https:\/\/aliensdesign.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#primaryimage"},"image":{"@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#primaryimage"},"thumbnailUrl":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png","datePublished":"2023-12-15T17:30:38+00:00","dateModified":"2024-04-18T17:24:33+00:00","author":{"@id":"https:\/\/aliensdesign.com.br\/#\/schema\/person\/a7f1f390dd8f2e971941a7e1835bfbdd"},"description":"Voc\u00ea j\u00e1 parou para pensar na import\u00e2ncia da tipografia no design gr\u00e1fico? Muitas vezes subestimada, a escolha da fonte certa \u00e9 crucial.","breadcrumb":{"@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#primaryimage","url":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png","contentUrl":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2023\/12\/configuracao-plana-das-letras-do-alfabeto-para-o-dia-da-educacao.png","width":6720,"height":4480},{"@type":"BreadcrumbList","@id":"https:\/\/aliensdesign.com.br\/2023\/12\/tipografia-como-escolher-a-fonte-para-o-seu-projeto-grafico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/aliensdesign.com.br\/"},{"@type":"ListItem","position":2,"name":"Tipografia: como escolher a fonte para o seu projeto"}]},{"@type":"WebSite","@id":"https:\/\/aliensdesign.com.br\/#website","url":"https:\/\/aliensdesign.com.br\/","name":"Aliens Design","description":"Ag\u00eancia de Design em Curitiba!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aliensdesign.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/aliensdesign.com.br\/#\/schema\/person\/a7f1f390dd8f2e971941a7e1835bfbdd","name":"Aliens Design","sameAs":["https:\/\/aliensdesign.com.br","https:\/\/www.facebook.com\/AliensDesign\/","https:\/\/www.instagram.com\/aliensdesign\/","https:\/\/www.linkedin.com\/company\/aliens-design\/"],"url":"https:\/\/aliensdesign.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/posts\/110918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/comments?post=110918"}],"version-history":[{"count":9,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/posts\/110918\/revisions"}],"predecessor-version":[{"id":111125,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/posts\/110918\/revisions\/111125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/media\/110922"}],"wp:attachment":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/media?parent=110918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/categories?post=110918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/tags?post=110918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}