{"id":79511,"date":"2019-08-07T14:15:09","date_gmt":"2019-08-07T17:15:09","guid":{"rendered":"http:\/\/u801642641.hostingerapp.com\/?post_type=portfolio&#038;p=79511"},"modified":"2021-02-10T16:46:34","modified_gmt":"2021-02-10T19:46:34","slug":"volvo-voam","status":"publish","type":"portfolio","link":"https:\/\/aliensdesign.com.br\/en\/portfolio\/volvo-voam\/","title":{"rendered":"VOLVO &#8211; VOAM"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-dark\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode_text_column\" ><p><span style=\"font-weight: 400;\">VOAM \u00e9 o plano de sa\u00fade do colaborador VOLVO. A aliens foi respons\u00e1vel por criar um site dentro das especifica\u00e7\u00f5es do Google, que comportasse a diferencia\u00e7\u00e3o da \u00e1rea de prestadores de servi\u00e7os de sa\u00fade e os usu\u00e1rios do plano de sa\u00fade.\u00a0<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-1\"><div class=\"row full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-dark\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"gallery-123450\" class=\"un-media-gallery isotope-system isotope-general-dark grid-general-dark\">\n\t\t\t\t\t\n\t\n\t<div class=\"isotope-wrapper grid-wrapper no-gutter\" >\n\t\t\t\t\t\t\t\t\t<div class=\"isotope-container isotope-layout style-masonry\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\">\n<div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80872  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.3%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80872\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/01-5.png\" width=\"1920\" height=\"1080\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/01-5.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/01-5-300x169.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/01-5-1024x576.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/01-5-768x432.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/01-5-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80873  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.3%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"1\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80873\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png\" width=\"1920\" height=\"1080\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5-300x169.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5-1024x576.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5-768x432.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80874  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 27.7%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"2\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80874\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/03-4.png\" width=\"1920\" height=\"532\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/03-4.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/03-4-300x83.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/03-4-1024x284.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/03-4-768x213.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/03-4-1536x426.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80875  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 84.8%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"3\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80875\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/04-5.png\" width=\"1920\" height=\"1629\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/04-5.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/04-5-300x255.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/04-5-1024x869.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/04-5-768x652.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/04-5-1536x1303.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80876  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.3%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"4\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80876\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/05-5.png\" width=\"1920\" height=\"1080\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/05-5.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/05-5-300x169.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/05-5-1024x576.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/05-5-768x432.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/05-5-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80877  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.3%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"5\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80877\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/06-4.png\" width=\"1920\" height=\"1080\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/06-4.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/06-4-300x169.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/06-4-1024x576.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/06-4-768x432.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/06-4-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80878  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.3%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"6\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80878\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/07-6.png\" width=\"1920\" height=\"1080\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/07-6.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/07-6-300x169.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/07-6-1024x576.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/07-6-768x432.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/07-6-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80879  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 56.3%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"7\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80879\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/08-2.png\" width=\"1920\" height=\"1080\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/08-2.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/08-2-300x169.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/08-2-1024x576.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/08-2-768x432.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/08-2-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-content-left tmb-bordered tmb-id-80880  tmb-content-under tmb-media-last tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 93.1%;\"><\/div><a role=\"button\" tabindex=\"-1\" class=\"inactive-link pushed\" data-lb-index=\"8\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.01;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-80880\" src=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/09-3.png\" width=\"1920\" height=\"1788\" alt=\"\" srcset=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/09-3.png 1920w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/09-3-300x279.png 300w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/09-3-1024x954.png 1024w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/09-3-768x715.png 768w, https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/09-3-1536x1430.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\t\n\t\n<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"VOAM \u00e9 o plano de sa\u00fade do colaborador VOLVO. A aliens foi respons\u00e1vel por criar um site dentro das especifica\u00e7\u00f5es [...]","protected":false},"author":1,"featured_media":80873,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"portfolio_category":[19],"class_list":["post-79511","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VOLVO - VOAM - Aliens Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aliensdesign.com.br\/en\/portfolio\/volvo-voam\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VOLVO - VOAM - Aliens Design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aliensdesign.com.br\/en\/portfolio\/volvo-voam\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliens Design\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T19:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/\",\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/\",\"name\":\"VOLVO - VOAM - Aliens Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/02-5.png\",\"datePublished\":\"2019-08-07T17:15:09+00:00\",\"dateModified\":\"2021-02-10T19:46:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/02-5.png\",\"contentUrl\":\"https:\\\/\\\/aliensdesign.com.br\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/02-5.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/volvo-voam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/aliensdesign.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/aliensdesign.com.br\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VOLVO &#8211; VOAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aliensdesign.com.br\\\/#website\",\"url\":\"https:\\\/\\\/aliensdesign.com.br\\\/\",\"name\":\"Aliens Design\",\"description\":\"Ag\u00eancia de Design em Curitiba!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aliensdesign.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VOLVO - VOAM - Aliens Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aliensdesign.com.br\/en\/portfolio\/volvo-voam\/","og_locale":"en_US","og_type":"article","og_title":"VOLVO - VOAM - Aliens Design","og_url":"https:\/\/aliensdesign.com.br\/en\/portfolio\/volvo-voam\/","og_site_name":"Aliens Design","article_modified_time":"2021-02-10T19:46:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/","url":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/","name":"VOLVO - VOAM - Aliens Design","isPartOf":{"@id":"https:\/\/aliensdesign.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/#primaryimage"},"image":{"@id":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/#primaryimage"},"thumbnailUrl":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png","datePublished":"2019-08-07T17:15:09+00:00","dateModified":"2021-02-10T19:46:34+00:00","breadcrumb":{"@id":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/#primaryimage","url":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png","contentUrl":"https:\/\/aliensdesign.com.br\/wp-content\/uploads\/2019\/08\/02-5.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/aliensdesign.com.br\/portfolio\/volvo-voam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/aliensdesign.com.br\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/aliensdesign.com.br\/portfolio\/"},{"@type":"ListItem","position":3,"name":"VOLVO &#8211; VOAM"}]},{"@type":"WebSite","@id":"https:\/\/aliensdesign.com.br\/#website","url":"https:\/\/aliensdesign.com.br\/","name":"Aliens Design","description":"Ag\u00eancia de Design em Curitiba!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aliensdesign.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio\/79511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/comments?post=79511"}],"version-history":[{"count":0,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio\/79511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/media\/80873"}],"wp:attachment":[{"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/media?parent=79511"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/aliensdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio_category?post=79511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}